{"id":263,"date":"2022-06-24T17:23:13","date_gmt":"2022-06-24T10:23:13","guid":{"rendered":"http:\/\/handapherang.desa.id\/cms\/?page_id=263"},"modified":"2022-06-26T11:47:57","modified_gmt":"2022-06-26T04:47:57","slug":"bpd-desa-handapherang","status":"publish","type":"page","link":"https:\/\/handapherang.desa.id\/cms\/bpd-desa-handapherang\/","title":{"rendered":"Badan Permusyawaratan Desa (BPD)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"263\" class=\"elementor elementor-263\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e75990 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e75990\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14f05d8\" data-id=\"14f05d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fe3ff7 elementor-widget elementor-widget-heading\" data-id=\"4fe3ff7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.6 - 08-06-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Testz<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\/*! elementor &#8211; v3.6.6 &#8211; 08-06-2022 *\/ .elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]&gt;a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px} Testz<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/pages\/263"}],"collection":[{"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":8,"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/pages\/263\/revisions"}],"predecessor-version":[{"id":517,"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/pages\/263\/revisions\/517"}],"wp:attachment":[{"href":"https:\/\/handapherang.desa.id\/cms\/wp-json\/wp\/v2\/media?parent=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}